{"id":99217,"date":"2026-08-12T16:00:21","date_gmt":"2026-08-12T15:00:21","guid":{"rendered":"https:\/\/avo-magazine.com\/?p=99217"},"modified":"2026-08-13T19:31:45","modified_gmt":"2026-08-13T18:31:45","slug":"voor-de-vijfde-keer-op-rij-keert-yutaro-ogida-terug-naar-europa-voor-een-tournee","status":"publish","type":"post","link":"https:\/\/avo-magazine.com\/nl\/2026\/08\/voor-de-vijfde-keer-op-rij-keert-yutaro-ogida-terug-naar-europa-voor-een-tournee\/","title":{"rendered":"Voor de vijfde keer op rij keert Yutaro Ogida terug naar Europa voor een tournee"},"content":{"rendered":"<p>Voor de vijfde keer op rij, komt rockmuzikant Yutaro Ogida weer richting Europa voor een tournee. De singer-songwriter liet in een socialemediabericht weten dat de Europese tournee in september zal plaatsvinden en uit zes optredens in het Verenigd Koninkrijk, Nederland en Zwitserland zal bestaan. Yutaro Ogida liet daarnaast nog weten dat het mogelijk is dat er nog een paar extra optredens worden toegevoegd aan de tourplanning.<br \/>\n<!--more--><\/p>\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"\u6247\u7530\u88d5\u592a\u90ce - \u6b20\u3051\u305f\u30e0\u30fc\u30f3\u30e9\u30a4\u30c8 (Official Music Video)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/9xSv9dUEtUY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p>Geboren in Tokyo, bracht\u00a0<a href=\"https:\/\/avo-magazine.com\/nl\/2024\/05\/avo-magazine-interview-met-yutaro-ogida-muziek-is-iets-dat-me-een-nieuwe-wereld-laat-zien\/\" target=\"_blank\" rel=\"noopener\">Yutaro Ogida<\/a> zijn jonge jaren door in New York en woonde hij in de tijd van zijn middelbare school in Londen. Dat was ook de periode waarin hij de gitaar voor het eerst oppakte. In de jaren \u201990 keerde hij terug in Japan en startte hij zijn professionele carri\u00e8re als gitarist. Ogida sloot zich aan bij verschillende bands en speelde veel sessies met verschillende muzikanten om zijn veelzijdigheid te kunnen laten zien. Uiteindelijk besloot de rockmuzikant zich te richten op zijn solomuziek en heeft twee mini-albums en een volwaardig album uitgebracht, <em>I AM<\/em>. Sindsdien is Yutaro Ogida meerdere keren naar Europa geweest voor optredens.<\/p>\n<p>Naast het feit dat hij solo actief is, is hij ook de medeoprichter van Genshi-Shinbo, een zeer bekend Pink Floyd-tribuutproject in Japan. Verder is hij actief in verschillende bands en dankzij al deze projecten is hij vrijwel dagelijks op de podia in Japan te vinden. Met \u00e9\u00e9n van de zijprojecten, WTARO, heeft Yutaro Ogida met rockzanger en bassist Showtaro Mitsuzono een 10 nummers tellend rockalbum met de titel <em>WTARO I<\/em> uitgebracht. In 2024 had AVO Magazine een <a href=\"https:\/\/avo-magazine.com\/nl\/2024\/05\/avo-magazine-interview-met-yutaro-ogida-muziek-is-iets-dat-me-een-nieuwe-wereld-laat-zien\/\" target=\"_blank\">interview<\/a> met Yutaro Ogida, waarin hij sprak over zijn muzikale reis.<\/p>\n<div class=\"jeg_video_container jeg_video_content\"><iframe loading=\"lazy\" title=\"WTARO - Super Rock&amp;apos;n&amp;apos;Roll (Official Music Video)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/TwGblgkVVCg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<h3>Yutaro Ogida Europese Tournee 2026 &#8211; Dates<\/h3>\n<p>Vrijdag 11 september 2026: Hope &#038; Anchor \u2013 Londen, Verenigd Koninkrijk<br \/>\nZondag 13 september 2026: Galerie Wijnand Driessen \u2013 Eindhoven, Nederland<br \/>\nDinsdag 15 september 2026: nader te bepalen \u2013 St. Gallen, Zwitserland<br \/>\nWoensdag 16 september 2026: nader te bepalen \u2013 St. Gallen, Zwitserland<br \/>\nDonderdag 17 september 2026: nader te bepalen \u2013 St. Gallen, Zwitserland<br \/>\nZondag 20 september 2026: Platteland \u2013 Utrecht, Nederland (Priv\u00e9optreden)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voor de vijfde keer op rij, komt rockmuzikant Yutaro Ogida weer richting Europa voor een tournee. De singer-songwriter liet in een socialemediabericht weten dat de Europese tournee in september zal plaatsvinden en uit zes optredens in het Verenigd Koninkrijk, Nederland en Zwitserland zal bestaan. Yutaro Ogida liet daarnaast nog weten dat het mogelijk is dat [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":81580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"subtitle":"","format":"standard","override":[{"template":"2","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"floatbottom","share_float_style":"share-monocrhome","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"1","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"no-crop","single_post_gallery_size":"crop-715"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","source_name":"Yutaro Ogida","source_url":"https:\/\/www.instagram.com\/p\/DbpL2xbz-vT\/"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[3738],"tags":[703,7757],"class_list":["post-99217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-japanse-muziek-evenementen","tag-rock","tag-rock-en-2"],"_links":{"self":[{"href":"https:\/\/avo-magazine.com\/nl\/wp-json\/wp\/v2\/posts\/99217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avo-magazine.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avo-magazine.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avo-magazine.com\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/avo-magazine.com\/nl\/wp-json\/wp\/v2\/comments?post=99217"}],"version-history":[{"count":8,"href":"https:\/\/avo-magazine.com\/nl\/wp-json\/wp\/v2\/posts\/99217\/revisions"}],"predecessor-version":[{"id":99239,"href":"https:\/\/avo-magazine.com\/nl\/wp-json\/wp\/v2\/posts\/99217\/revisions\/99239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avo-magazine.com\/nl\/wp-json\/wp\/v2\/media\/81580"}],"wp:attachment":[{"href":"https:\/\/avo-magazine.com\/nl\/wp-json\/wp\/v2\/media?parent=99217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avo-magazine.com\/nl\/wp-json\/wp\/v2\/categories?post=99217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avo-magazine.com\/nl\/wp-json\/wp\/v2\/tags?post=99217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}